{"id":2385,"date":"2021-05-11T05:02:12","date_gmt":"2021-05-11T08:02:12","guid":{"rendered":"https:\/\/www.encontracapaoredondo.com.br\/sobre\/?p=2385"},"modified":"2021-05-11T05:02:12","modified_gmt":"2021-05-11T08:02:12","slug":"ubs-jd-maraca-capao-redondo","status":"publish","type":"post","link":"https:\/\/www.encontracapaoredondo.com.br\/sobre\/ubs-jd-maraca-capao-redondo\/","title":{"rendered":"UBS Jd. Maraca Cap\u00e3o Redondo"},"content":{"rendered":"<div class=\"8fb9da09c1a584b185d8cf81e63b5046\" data-index=\"1\" style=\"float: none; margin:0px;\">\n<!-- Anuncio display - global -->\r\n<ins class=\"adsbygoogle\"\r\n     style=\"display:block\"\r\n     data-ad-client=\"ca-pub-8585364105181520\"\r\n     data-ad-slot=\"8789329856\"\r\n     data-ad-format=\"auto\"\r\n     data-full-width-responsive=\"true\"><\/ins>\r\n<script>\r\n     (adsbygoogle = window.adsbygoogle || []).push({});\r\n<\/script>\n<\/div>\n<p>A<strong> UBS Jd. Maraca Cap\u00e3o Redondo<\/strong>\u00a0\u00e9 uma unidade de atendimento de sa\u00fade onde encontram-se m\u00e9dicos, dentistas para atender \u00e0 popula\u00e7\u00e3o de um bairro ou de uma determinada regi\u00e3o.<\/p>\n<p>O atendimento deve ser gratuito e destina-se exclusivamente \u00e0 preven\u00e7\u00e3o. Os casos mais graves e\/ou urg\u00eancias, emerg\u00eancias, devem se encaminhar diretamente a um pronto-socorro (ou pronto-atendimento), onde h\u00e1 recursos adequados para tais atendimentos.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-2373 size-full\" title=\"UBS Jd. Maraca Cap\u00e3o Redondo\" src=\"https:\/\/www.encontracapaoredondo.com.br\/sobre\/wp-content\/uploads\/UBS-ARACAJU.gif\" alt=\"UBS Jd. Maraca Cap\u00e3o Redondo\" width=\"680\" height=\"189\" \/><\/p>\n<p>No posto de sa\u00fade ou UBS, o paciente agenda as consultas para preven\u00e7\u00e3o \u2014 ginecologista, obstetra, cl\u00ednico geral, pediatra, dentista, psiquiatra e tamb\u00e9m vacinas e acompanhamento de hipertens\u00e3o.<\/p>\n<p>Quando h\u00e1 necessidade de exames de m\u00e9dia e alta complexidade, especialidades m\u00e9dicas ou cirurgias, os pacientes s\u00e3o encaminhados para uma lista de espera de disponibilidade de vagas do governo do estado, pois a responsabilidade do munic\u00edpio (prefeitura) \u00e9 o atendimento b\u00e1sico. A rela\u00e7\u00e3o m\u00e9dico\/dentista varia de acordo com o estado; por exemplo, no Paran\u00e1 a rela\u00e7\u00e3o \u00e9 de um dentista para cada um m\u00e9dico.<ins class=\"adsbygoogle\" data-ad-layout=\"in-article\" data-ad-format=\"fluid\" data-ad-client=\"ca-pub-6414922941841817\" data-ad-slot=\"1158071521\" data-adsbygoogle-status=\"done\"><ins id=\"aswift_2_expand\"><ins id=\"aswift_2_anchor\"><\/ins><\/ins><\/ins><\/p>\n<h2>UBS Jd. Maraca Cap\u00e3o Redondo Fun\u00e7\u00e3o<\/h2>\n<p>As Unidades B\u00e1sicas de Sa\u00fade (UBS) s\u00e3o a\u00a0<em>porta de entrada<\/em>\u00a0preferencial do Sistema \u00danico de Sa\u00fade (SUS). O objetivo desses postos \u00e9 atender at\u00e9 80% dos problemas de sa\u00fade da popula\u00e7\u00e3o, sem que haja a necessidade de encaminhamento para outros servi\u00e7os, como emerg\u00eancias e hospitais.<\/p>\n<p>Promover e proteger a sa\u00fade, a preven\u00e7\u00e3o de agravos, o diagn\u00f3stico, o tratamento, a reabilita\u00e7\u00e3o, a redu\u00e7\u00e3o de danos e a manuten\u00e7\u00e3o da sa\u00fade com o objetivo de desenvolver uma aten\u00e7\u00e3o integral que impacte na situa\u00e7\u00e3o de sa\u00fade e autonomia das pessoas e nos determinantes e condicionantes de sa\u00fade das coletividades.<\/p>\n<p>A Unidade B\u00e1sica de Sa\u00fade (UBS) \u00e9 o contato preferencial dos usu\u00e1rios, a principal porta de entrada e centro de comunica\u00e7\u00e3o com toda a Rede de Aten\u00e7\u00e3o \u00e0 Sa\u00fade. \u00c9 instalada perto de onde as pessoas moram, trabalham, estudam e vivem e, com isso, desempenha um papel central na garantia de acesso \u00e0 popula\u00e7\u00e3o a uma aten\u00e7\u00e3o \u00e0 sa\u00fade de qualidade.<\/p>\n<h3>Atendimento na UBS<\/h3>\n<p>Na UBS, \u00e9 poss\u00edvel receber\u00a0<em>atendimentos<\/em>\u00a0b\u00e1sicos e gratuitos em Pediatria, Ginecologia, Cl\u00ednica Geral, Enfermagem e Odontologia. Os principais servi\u00e7os oferecidos s\u00e3o consultas m\u00e9dicas, inala\u00e7\u00f5es, inje\u00e7\u00f5es, curativos, vacinas, coleta de exames laboratoriais, tratamento odontol\u00f3gico, encaminhamentos para especialidades e fornecimento de medica\u00e7\u00e3o b\u00e1sica.<\/p>\n<h3>Quando n\u00e3o procurar a UBS<\/h3>\n<p>Nas UBSs\u00a0\u00a0<em>N\u00c3O s\u00e3o realizados<\/em>\u00a0atendimentos de emerg\u00eancia e procedimentos como: cirurgias; consultas t\u00edpicas de ambulat\u00f3rios de aten\u00e7\u00e3o especializada como com o cardiologista e para tratamento de c\u00e2ncer; transfus\u00f5es de sangue; realiza\u00e7\u00e3o de exames diagn\u00f3sticos como raio x, teste de esfor\u00e7o, tomografia etc.<\/p>\n<h3>Vagas UBS Jd. Maraca Cap\u00e3o Redondo \u2013 Trabalhe Conosco<\/h3>\n<p>A UBS Jd. Maraca Cap\u00e3o Redondo disponibiliza <em>vagas de trabalho<\/em>\u00a0durante todo ano. Para se informar sobre os processos seletivos e se candidatar as vagas acompanhe o site da empresa, onde \u00e9 poss\u00edvel se informar sobre vagas abertas, sal\u00e1rios e compet\u00eancias necess\u00e1rias para se candidatar ao processo.<\/p>\n<h3>Hor\u00e1rio de Funcionamento UBS Jd. Maraca no Cap\u00e3o Redondo<\/h3>\n<ul>\n<li>Segunda a Sexta das 07h \u00e0s 17h<\/li>\n<\/ul>\n<h3>Endere\u00e7o e Telefone UBS Jd. Maraca no Cap\u00e3o Redondo<\/h3>\n<ul>\n<li>Rua Feres Bechara, 506 &#8211; Cap\u00e3o Redondo &#8211; S\u00e3o Paulo &#8211; SP<\/li>\n<li>Telefone: (11) 5874-4720<\/li>\n<\/ul>\n<h4>Mapa de localiza\u00e7\u00e3o<\/h4>\n<a class=\"wp-colorbox-iframe\" href=\"https:\/\/www.google.com\/maps\/embed?pb=!1m14!1m8!1m3!1d14616.482566598224!2d-46.7727496!3d-23.6716433!3m2!1i1024!2i768!4f13.1!3m3!1m2!1s0x00x77dfb36e31a90cff!2zw5puaWRhZGUgQsOhc2ljYSBkZSBTYcO6ZGUgSmFyZGltIE1hcmFjw6E!5e0!3m2!1spt-BR!2sbr!4v1620720022812!5m2!1spt-BR!2sbr\"><img decoding=\"async\" src=\"http:\/\/www.encontracapaoredondo.com.br\/imgs\/maps-post.png\"><\/a>\n\n<div style=\"font-size: 0px; height: 0px; line-height: 0px; margin: 0; padding: 0; clear: both;\"><\/div>","protected":false},"excerpt":{"rendered":"<p>A UBS Jd. Maraca Cap\u00e3o Redondo\u00a0\u00e9 uma unidade de atendimento de sa\u00fade onde encontram-se m\u00e9dicos, dentistas para atender \u00e0 popula\u00e7\u00e3o de um bairro ou de uma determinada regi\u00e3o. O atendimento deve ser gratuito e destina-se exclusivamente \u00e0 preven\u00e7\u00e3o. Os casos mais graves e\/ou urg\u00eancias, emerg\u00eancias, devem se encaminhar diretamente a um pronto-socorro (ou pronto-atendimento), onde h\u00e1 recursos adequados para tais atendimentos. No posto de sa\u00fade ou UBS, o paciente agenda as consultas para preven\u00e7\u00e3o \u2014 ginecologista, obstetra, cl\u00ednico geral, pediatra, dentista, psiquiatra e tamb\u00e9m vacinas e acompanhamento de hipertens\u00e3o. Quando h\u00e1 necessidade de exames de m\u00e9dia e alta complexidade, especialidades <\/p>\n","protected":false},"author":1,"featured_media":2373,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[31],"tags":[],"class_list":["post-2385","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-saude-no-capao-redondo","has_thumb"],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/www.encontracapaoredondo.com.br\/sobre\/wp-json\/wp\/v2\/posts\/2385","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.encontracapaoredondo.com.br\/sobre\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.encontracapaoredondo.com.br\/sobre\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.encontracapaoredondo.com.br\/sobre\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.encontracapaoredondo.com.br\/sobre\/wp-json\/wp\/v2\/comments?post=2385"}],"version-history":[{"count":0,"href":"https:\/\/www.encontracapaoredondo.com.br\/sobre\/wp-json\/wp\/v2\/posts\/2385\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.encontracapaoredondo.com.br\/sobre\/wp-json\/wp\/v2\/media\/2373"}],"wp:attachment":[{"href":"https:\/\/www.encontracapaoredondo.com.br\/sobre\/wp-json\/wp\/v2\/media?parent=2385"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.encontracapaoredondo.com.br\/sobre\/wp-json\/wp\/v2\/categories?post=2385"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.encontracapaoredondo.com.br\/sobre\/wp-json\/wp\/v2\/tags?post=2385"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}