{"id":2329,"date":"2020-01-30T05:34:16","date_gmt":"2020-01-30T08:34:16","guid":{"rendered":"https:\/\/www.encontracapaoredondo.com.br\/sobre\/?p=2329"},"modified":"2021-09-20T09:41:59","modified_gmt":"2021-09-20T12:41:59","slug":"lavoisier-capao-redondo","status":"publish","type":"post","link":"https:\/\/www.encontracapaoredondo.com.br\/sobre\/lavoisier-capao-redondo\/","title":{"rendered":"Lavoisier Cap\u00e3o Redondo"},"content":{"rendered":"<div class=\"8fb9da09c1a584b185d8cf81e63b5046\" data-index=\"1\" style=\"float: none; margin:0px;\">\n<!-- Anuncio display - global -->\r\n<ins class=\"adsbygoogle\"\r\n     style=\"display:block\"\r\n     data-ad-client=\"ca-pub-8585364105181520\"\r\n     data-ad-slot=\"8789329856\"\r\n     data-ad-format=\"auto\"\r\n     data-full-width-responsive=\"true\"><\/ins>\r\n<script>\r\n     (adsbygoogle = window.adsbygoogle || []).push({});\r\n<\/script>\n<\/div>\n<p>O Lavoisier foi fundado em 1951, em S\u00e3o Paulo, por tr\u00eas estudantes de medicina e um qu\u00edmico, como Bio-Ci\u00eancia Lavoisier. Com o tempo, al\u00e9m dos <em>exames laboratoriais<\/em>\u00a0passou a oferecer tamb\u00e9m servi\u00e7os de diagn\u00f3sticos por imagem.<\/p>\n<p>O Lavoisier foi o primeiro laborat\u00f3rio brasileiro a receber a Certifica\u00e7\u00e3o de Qualidade ISO 9002 em todos os seus processos e foi pioneiro na implanta\u00e7\u00e3o de unidades em shopping centers e hipermercados, entre elas o\u00a0<strong>Lavoisier Cap\u00e3o Redondo.<\/strong><\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-2330 size-full\" title=\"Lavoisier Cap\u00e3o Redondo\" src=\"https:\/\/www.encontracapaoredondo.com.br\/sobre\/wp-content\/uploads\/lavoisier-capao.gif\" alt=\"Lavoisier Cap\u00e3o Redondo\" width=\"680\" height=\"189\" \/><\/p>\n<p>Com o objetivo de oferecer exames de qualidade a todas as classes sociais, o Lavoisier lan\u00e7ou, em 2006, o projeto Lavoisier Popular, hoje presente em todas as\u00a0mais de 50 unidades\u00a0da marca na Grande S\u00e3o Paulo e no interior.<\/p>\n<h2>Lavoisier Cap\u00e3o Redondo Hist\u00f3ria<\/h2>\n<p>O Lavoisier foi fundado em 1951, em S\u00e3o Paulo, por tr\u00eas estudantes de medicina e um qu\u00edmico, como Bio-Ci\u00eancia Lavoisier. Com o tempo, al\u00e9m dos exames laboratoriais passou a oferecer tamb\u00e9m servi\u00e7os de diagn\u00f3sticos por imagem.<\/p>\n<p>Em 1999, com 14 unidades de atendimento, foi incorporado \u00e0 marca Delboni Auriemo, formando, em 2000, a Diagn\u00f3sticos da Am\u00e9rica S.A. (Dasa), maior empresa de Medicina Diagn\u00f3stica da Am\u00e9rica Latina. O Lavoisier foi o primeiro laborat\u00f3rio brasileiro a receber a Certifica\u00e7\u00e3o de Qualidade ISO 9002 em todos os seus processos e foi pioneiro na implanta\u00e7\u00e3o de unidades em shopping centers e hipermercados.\u00a0Com o objetivo de oferecer exames de qualidade a todas as classes sociais, o Lavoisier lan\u00e7ou, em 2006, o projeto Lavoisier Popular, hoje presente em todas as mais de 90 unidades da marca, onde oferece condi\u00e7\u00f5es de pagamento especiais para seus pacientes.<\/p>\n<h3>Lavoisier Cap\u00e3o Redondo Exames<\/h3>\n<ul>\n<li>Citogen\u00e9tica<\/li>\n<li>Agrega\u00e7\u00e3o plaquet\u00e1ria<\/li>\n<li>Ambulatorial<\/li>\n<li>An\u00e1lises cl\u00ednicas<\/li>\n<li>Anatomia patol\u00f3gica<\/li>\n<li>Biologia molecular<\/li>\n<li>Sexagem fetal<\/li>\n<\/ul>\n<p>Consulte o site para encontrar o<em>\u00a0exame<\/em>\u00a0que voc\u00ea precisa.<\/p>\n<h3>Lavoisier Cap\u00e3o Redondo Popular<\/h3>\n<p>O programa\u00a0<em>Lavoisier Popular<\/em>\u00a0foi criado para voc\u00ea que n\u00e3o tem plano de sa\u00fade.\u00a0Com ele, voc\u00ea realiza os exames laboratoriais e de imagem indicados\u00a0pelo seu m\u00e9dico\u00a0com qualidade e seguran\u00e7a, de forma acess\u00edvel.\u00a0S\u00e3o mais de 60 unidades dispon\u00edveis, na Grande S\u00e3o Paulo e no Interior.\u00a0Com certeza, uma pertinho de voc\u00ea.<\/p>\n<h3>Lavoisier Cap\u00e3o Redondo Resultado de Exames<\/h3>\n<p>Para sua maior comodidade, o\u00a0<strong>Lavoisier Cap\u00e3o Redondo<\/strong>\u00a0disponibiliza os\u00a0<span style=\"text-decoration: underline;\">resultados dos seus exames<\/span>\u00a0em seu site. Basta acessar o site e clicar em exames. Utilize o n\u00famero de protocolo e senha recebidos no dia da realiza\u00e7\u00e3o dos exames<em>.<\/em><\/p>\n<h3>Hor\u00e1rio de Funcionamento Lavoisier em Cap\u00e3o Redondo<\/h3>\n<ul>\n<li>Segunda a S\u00e1bado da 06h \u00e0s 13h.<\/li>\n<\/ul>\n<h3>Endere\u00e7o e Telefone Lavoisier em Cap\u00e3o Redondo<\/h3>\n<ul>\n<li>Av. Ellis Maas, 641 &#8211; 9 &#8211; Cap\u00e3o Redondo &#8211; S\u00e3o Paulo &#8211; SP<\/li>\n<li>Telefone: (11) 3047-4488<\/li>\n<\/ul>\n<h4>Outras informa\u00e7\u00f5es e site<\/h4>\n<ul>\n<li>Mais informa\u00e7\u00f5es:\u00a0<a href=\"http:\/\/www.lavoisier.com.br\/\" target=\"_blank\" rel=\"noopener noreferrer\">www.lavoisier.com.br\/<\/a><\/li>\n<\/ul>\n<h4>Mapa de localiza\u00e7\u00e3o<\/h4>\n<a class=\"wp-colorbox-iframe\" href=\"https:\/\/www.google.com\/maps\/embed?pb=!1m14!1m8!1m3!1d14617.142594739957!2d-46.7704339!3d-23.6657407!3m2!1i1024!2i768!4f13.1!3m3!1m2!1s0x00x7acb5476bfd4e151!2sLavoisierCapoRedondo!5e0!3m2!1spt-BR!2sbr!4v1580373039945!5m2!1spt-BR!2sbr\"><img decoding=\"async\" src=\"http:\/\/www.encontracapaoredondo.com.br\/imgs\/maps-post.png\"><\/a>\n\n<div style=\"font-size: 0px; height: 0px; line-height: 0px; margin: 0; padding: 0; clear: both;\"><\/div>","protected":false},"excerpt":{"rendered":"<p>O Lavoisier foi fundado em 1951, em S\u00e3o Paulo, por tr\u00eas estudantes de medicina e um qu\u00edmico, como Bio-Ci\u00eancia Lavoisier. Com o tempo, al\u00e9m dos exames laboratoriais\u00a0passou a oferecer tamb\u00e9m servi\u00e7os de diagn\u00f3sticos por imagem. O Lavoisier foi o primeiro laborat\u00f3rio brasileiro a receber a Certifica\u00e7\u00e3o de Qualidade ISO 9002 em todos os seus processos e foi pioneiro na implanta\u00e7\u00e3o de unidades em shopping centers e hipermercados, entre elas o\u00a0Lavoisier Cap\u00e3o Redondo. Com o objetivo de oferecer exames de qualidade a todas as classes sociais, o Lavoisier lan\u00e7ou, em 2006, o projeto Lavoisier Popular, hoje presente em todas as\u00a0mais de <\/p>\n","protected":false},"author":1,"featured_media":2330,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[31],"tags":[],"class_list":["post-2329","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-saude-no-capao-redondo","has_thumb"],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/www.encontracapaoredondo.com.br\/sobre\/wp-json\/wp\/v2\/posts\/2329","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.encontracapaoredondo.com.br\/sobre\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.encontracapaoredondo.com.br\/sobre\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.encontracapaoredondo.com.br\/sobre\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.encontracapaoredondo.com.br\/sobre\/wp-json\/wp\/v2\/comments?post=2329"}],"version-history":[{"count":0,"href":"https:\/\/www.encontracapaoredondo.com.br\/sobre\/wp-json\/wp\/v2\/posts\/2329\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.encontracapaoredondo.com.br\/sobre\/wp-json\/wp\/v2\/media\/2330"}],"wp:attachment":[{"href":"https:\/\/www.encontracapaoredondo.com.br\/sobre\/wp-json\/wp\/v2\/media?parent=2329"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.encontracapaoredondo.com.br\/sobre\/wp-json\/wp\/v2\/categories?post=2329"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.encontracapaoredondo.com.br\/sobre\/wp-json\/wp\/v2\/tags?post=2329"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}